{"id":233482,"date":"2023-01-29T23:43:51","date_gmt":"2023-01-29T22:43:51","guid":{"rendered":"https:\/\/divesterram.fr\/?page_id=233482"},"modified":"2026-02-02T10:03:27","modified_gmt":"2026-02-02T09:03:27","slug":"tarifs","status":"publish","type":"page","link":"https:\/\/divesterram.fr\/index.php\/tarifs\/","title":{"rendered":"Tarifs 2026"},"content":{"rendered":"\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><em><strong>Tous nos prix sont H.T. et n&rsquo;incluent pas le service de livraison. Nos mod\u00e8les sont d\u00e9pos\u00e9s, leur reproduction est interdite.<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"928\" src=\"https:\/\/divesterram.fr\/wp-content\/uploads\/2025\/11\/dessin4-psp-scaled-1-1024x928.jpg\" alt=\"\" class=\"wp-image-586720\" style=\"width:392px;height:auto\" srcset=\"https:\/\/divesterram.fr\/wp-content\/uploads\/2025\/11\/dessin4-psp-scaled-1-1024x928.jpg 1024w, https:\/\/divesterram.fr\/wp-content\/uploads\/2025\/11\/dessin4-psp-scaled-1-300x272.jpg 300w, https:\/\/divesterram.fr\/wp-content\/uploads\/2025\/11\/dessin4-psp-scaled-1-768x696.jpg 768w, https:\/\/divesterram.fr\/wp-content\/uploads\/2025\/11\/dessin4-psp-scaled-1-1536x1393.jpg 1536w, https:\/\/divesterram.fr\/wp-content\/uploads\/2025\/11\/dessin4-psp-scaled-1-2048x1857.jpg 2048w, https:\/\/divesterram.fr\/wp-content\/uploads\/2025\/11\/dessin4-psp-scaled-1-1200x1088.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">Les monobac:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"#B6\"><strong>Le 600<\/strong> litres <strong>1 fa\u00e7ade et 1 capot<\/strong> \u00e0 480 \u20ac HT.<\/li>\n\n\n\n<li><strong>Le 800<\/strong> litres <strong>2 fa\u00e7ades et 1 capot<\/strong> \u00e0 560\u20ac HT.<\/li>\n\n\n\n<li><strong>Le 1000<\/strong> litres <strong>2 fa\u00e7ades et 2 capots<\/strong> \u00e0 670\u20ac HT.<\/li>\n\n\n\n<li>Les grilles basses anti-rat en option:<\/li>\n\n\n\n<li>Kit grille 600: 87\u20ac HT.<\/li>\n\n\n\n<li>Kit grille 800: 98\u20ac HT.<\/li>\n\n\n\n<li>Kit grille 1000: 110\u20ac HT.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Les tribacs:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Le 1800<\/strong> litres <strong>(3 bacs)<\/strong> cr\u00e9\u00e9 sp\u00e9cialement pour les quartiers \u00e0 1323 \u20ac HT.<\/li>\n\n\n\n<li><strong>Le 2400<\/strong> litres <strong>(3 bacs)<\/strong> cr\u00e9\u00e9 sp\u00e9cialement pour les quartiers \u00e0 1564 \u20ac HT.<\/li>\n\n\n\n<li>Les grilles basses anti-rat en option:<\/li>\n\n\n\n<li>Kit grille 1800: 160\u20ac HT.<\/li>\n\n\n\n<li>Kit grille 2400: 187\u20ac HT.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Les pavillons grande capacit\u00e9:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les pavillons: mod\u00e8les \u00e9volutifs \u00e0 partir de 4700\u20ac HT install\u00e9.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Les accessoires: <\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les Coffres \u00e0 outils \u00e0 210\u20ac HT.<\/li>\n\n\n\n<li>Les portes panneaux \u00e0 28\u20ac HT.<\/li>\n\n\n\n<li>Les gravures de logos \u00e0 20\u20ac HT format .<\/li>\n\n\n\n<li>Les kits grilles anti-rat.<\/li>\n\n\n\n<li>Les bacs rubans \u00e0 compost mature.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Les mod\u00e8les sp\u00e9ciaux:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Le 400 litres<\/strong> (sp\u00e9cial classe 4 car en ch\u00e2taigner) 390\u20ac HT.<\/li>\n\n\n\n<li>Le 900 litres Entreprises \u00e0 970\u20ac HT.<\/li>\n\n\n\n<li>Le 2400 Litres Renforc\u00e9 anti humidit\u00e9 \u00e0 1680\u20ac HT.<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading\">Les monobac:<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/compost.equipment\/wp-content\/uploads\/2025\/01\/IMG_20240829_111325-1-1024x768.jpg\" alt=\"\" class=\"wp-image-134\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nous avons con\u00e7u ces mod\u00e8les pour une utilisation en tous lieu et pour augmenter le volume des installations tribacs 1800 et 2400 litres.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tous les bacs sont identiques de face quelque soit leur volume, la profondeur et la largeur  varie selon les volumes.<\/p>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<h3 class=\"wp-block-heading\" id=\"600litres\">&#8211; <strong>Le 600litres<\/strong>:<\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/compost.equipment\/wp-content\/uploads\/2025\/01\/L1130036-1024x768.jpg\" alt=\"\" class=\"wp-image-207\"\/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>1 capot et 1 ouverture en fa\u00e7ade.<\/strong><\/li>\n\n\n\n<li><strong>Capacit\u00e9 de traitement :<\/strong>&nbsp;600 litres utiles + 55litres en moyenne, pour le d\u00e9gazage avec effet acc\u00e9l\u00e9rateur.<\/li>\n\n\n\n<li><strong>Ing\u00e9nierie super fiable :<\/strong>&nbsp;Notre exp\u00e9rience de dix ans de cr\u00e9ation de composteurs vous garantit un fonctionnement optimal pour des ann\u00e9es de service en tous lieux et toute m\u00e9t\u00e9o.<\/li>\n\n\n\n<li><strong>Montage facile :<\/strong>&nbsp;Livr\u00e9 en kit, le montage se fait en 25minutes avec une visseuse. L\u2019assemblage peut se faire par une personne seule et la notice ainsi que la visserie sont fournis dans le kit.<\/li>\n\n\n\n<li><strong>Dur\u00e9e de vie :<\/strong>&nbsp;R\u00e9alis\u00e9 avec sens et passion, nos composteurs ne sont pas cens\u00e9s casser avant 6 \u00e0 10 ans ou plus (suivant les contraintes locales). Ce mod\u00e8le con\u00e7u avec les m\u00eames mat\u00e9riaux que les gros composteurs b\u00e9n\u00e9ficient d\u2019une solidit\u00e9 extr\u00eame.<\/li>\n\n\n\n<li><strong>Entretien :<\/strong>&nbsp;Aucun entretien n\u2019est n\u00e9cessaire gr\u00e2ce \u00e0 la haute qualit\u00e9 de tous nos mat\u00e9riaux. Le bois ne doit pas \u00eatre impr\u00e9gn\u00e9 de substance qui pourrait entraver sa fonction r\u00e9gulant l\u2019humidit\u00e9.<\/li>\n\n\n\n<li><strong>Informations compl\u00e9mentaires :<\/strong>\u00a0Merci de consulter la fiche de pr\u00e9sentation technique sur le site internet divesterram.fr.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"800litres\">&#8211; <strong>Le 800 litres :<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/compost.equipment\/wp-content\/uploads\/2025\/01\/cropped-IMG_20240829_124213-scaled-1-1024x238.jpg\" alt=\"\" class=\"wp-image-157\"\/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>1 capot et double ouverture en fa\u00e7ade<\/strong>.<\/li>\n\n\n\n<li><strong>Capacit\u00e9 de traitement :<\/strong>&nbsp;800 litres utiles + 70litres en moyenne, pour le d\u00e9gazage avec effet acc\u00e9l\u00e9rateur.<\/li>\n\n\n\n<li><strong>Ing\u00e9nierie super fiable :<\/strong>&nbsp;Notre exp\u00e9rience de dix ans de cr\u00e9ation de composteurs vous garantit un fonctionnement optimal pour des ann\u00e9es de service en tous lieux et toute m\u00e9t\u00e9o.<\/li>\n\n\n\n<li><strong>Montage facile :<\/strong>&nbsp;Livr\u00e9 en kit, le montage se fait en 25minutes avec une visseuse. L\u2019assemblage peut se faire par une personne seule et la notice ainsi que la visserie sont fournis dans le kit.<\/li>\n\n\n\n<li><strong>Dur\u00e9e de vie :<\/strong>&nbsp;R\u00e9alis\u00e9 avec sens et passion, nos composteurs ne sont pas cens\u00e9s casser avant 6 \u00e0 10 ans ou plus (suivant les contraintes locales). Ce mod\u00e8le con\u00e7u avec les m\u00eames mat\u00e9riaux que les gros composteurs b\u00e9n\u00e9ficient d\u2019une solidit\u00e9 extr\u00eame.<\/li>\n\n\n\n<li><strong>Entretien :<\/strong>&nbsp;Aucun entretien n\u2019est n\u00e9cessaire gr\u00e2ce \u00e0 la haute qualit\u00e9 de tous nos mat\u00e9riaux. Le bois ne doit pas \u00eatre impr\u00e9gn\u00e9 de substance qui pourrait entraver sa fonction r\u00e9gulant l\u2019humidit\u00e9.<\/li>\n\n\n\n<li><strong>Informations compl\u00e9mentaires :<\/strong>&nbsp;Merci de consulter la fiche de pr\u00e9sentation technique sur le site internet divesterram.fr.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"1000litres\">&#8211; <strong>Le 1000 litres sp\u00e9cial bac d\u2019apport :<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/compost.equipment\/wp-content\/uploads\/2025\/01\/IMG_20250113_161902-edited.jpg\" alt=\"\" class=\"wp-image-209\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2 capots et double ouverture en fa\u00e7ade.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Capacit\u00e9 de traitement :<\/strong>&nbsp;1000 litres utiles + 90litres en moyenne, pour le d\u00e9gazage avec effet acc\u00e9l\u00e9rateur.<\/li>\n\n\n\n<li><strong>Ing\u00e9nierie super fiable :<\/strong>&nbsp;Notre exp\u00e9rience de dix ans de cr\u00e9ation de composteurs vous garantit un fonctionnement optimal pour des ann\u00e9es de service en tous lieux et toute m\u00e9t\u00e9o.<\/li>\n\n\n\n<li><strong>Montage facile :<\/strong>&nbsp;Livr\u00e9 en kit, le montage se fait en 25minutes avec une visseuse. L\u2019assemblage peut se faire par une personne seule et la notice ainsi que la visserie sont fournis dans le kit.<\/li>\n\n\n\n<li><strong>Dur\u00e9e de vie :<\/strong>&nbsp;R\u00e9alis\u00e9 avec sens et passion, nos composteurs ne sont pas cens\u00e9s casser avant 6 \u00e0 10 ans ou plus (suivant les contraintes locales). Ce mod\u00e8le con\u00e7u avec les m\u00eames mat\u00e9riaux que les gros composteurs b\u00e9n\u00e9ficient d\u2019une solidit\u00e9 extr\u00eame.<\/li>\n\n\n\n<li><strong>Entretien :<\/strong>&nbsp;Aucun entretien n\u2019est n\u00e9cessaire gr\u00e2ce \u00e0 la haute qualit\u00e9 de tous nos mat\u00e9riaux. Le bois ne doit pas \u00eatre impr\u00e9gn\u00e9 de substance qui pourrait entraver sa fonction r\u00e9gulant l\u2019humidit\u00e9.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les tribacs:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1800litres\">&#8211; <strong>Le 1800 litres:<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/compost.equipment\/wp-content\/uploads\/2025\/01\/image-1.jpeg\" alt=\"\" class=\"wp-image-185\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3 bacs de 600 litres<\/strong>&nbsp;= 1 bac d\u2019apport de 600 litres + 1 bac de r\u00e9serve de mati\u00e8re s\u00e8che de 600 litres + 1 bac de maturation de 600litres litres, volume conseill\u00e9 pour 20 foyers. Dimensions au sol : 250 x 88 cm.&nbsp;<strong>Prix du 1800 : 1323,00\u20ac<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En option le kit anti rat : 160\u20ac<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le module suppl\u00e9mentaire associ\u00e9 est le mono bac 600 litres<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix du module suppl\u00e9mentaire : 480,00\u20ac<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Capacit\u00e9 de traitement :<\/strong>&nbsp;1800 litres utiles + 120litres en moyenne, pour le d\u00e9gazage avec effet acc\u00e9l\u00e9rateur dans les compartiments apport et maturation. 3 bacs en 1 meuble avec 600 litres pour l\u2019apport, 600litres pour le broyat, 600 litres pour la maturation.<\/li>\n\n\n\n<li><strong>Ing\u00e9nierie super fiable :<\/strong>&nbsp;Notre exp\u00e9rience de dix ans de cr\u00e9ation de composteurs vous garantit un fonctionnement optimal pour des ann\u00e9es de service en tous lieux et toute m\u00e9t\u00e9o.<\/li>\n\n\n\n<li><strong>Montage facile :<\/strong>&nbsp;Livr\u00e9 en kit, le montage se fait en 25minutes avec une visseuse. L\u2019assemblage peut se faire par une personne seule et la notice ainsi que la visserie sont fournis dans le kit.<\/li>\n\n\n\n<li><strong>Dur\u00e9e de vie :<\/strong>&nbsp;R\u00e9alis\u00e9 avec sens et passion, nos composteurs ne sont pas cens\u00e9s casser avant 6 \u00e0 10 ans ou plus (suivant les contraintes locales). Ce mod\u00e8le con\u00e7u avec les m\u00eames mat\u00e9riaux que les gros composteurs b\u00e9n\u00e9ficient d\u2019une solidit\u00e9 extr\u00eame.<\/li>\n\n\n\n<li><strong>Entretien :<\/strong>&nbsp;Aucun entretien n\u2019est n\u00e9cessaire gr\u00e2ce \u00e0 la haute qualit\u00e9 de tous nos mat\u00e9riaux. Le bois ne doit pas \u00eatre impr\u00e9gn\u00e9 de substance qui pourrait entraver sa fonction r\u00e9gulant l\u2019humidit\u00e9.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2400litres\">&#8211; Le 2400 litres :<\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/compost.equipment\/wp-content\/uploads\/2025\/01\/20240712_130210-edited-scaled.jpg\" alt=\"\" class=\"wp-image-211\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3 bacs de 800 litres<\/strong>&nbsp;= 1 bac d\u2019apport de 800 litres + 1 bac de r\u00e9serve de mati\u00e8re s\u00e8che de 800 litres + 1 bac de maturation de 800litres litres. Conseill\u00e9 pour 30 foyers. Dimensions au sol : 300 x 98 cm.&nbsp;<strong>Prix du 2400 : 1564,00\u20ac.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le module suppl\u00e9mentaire associ\u00e9 est le mono bac 800 litres<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prix du module suppl\u00e9mentaire : 560,00\u20ac<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Capacit\u00e9 de traitement :<\/strong>&nbsp;2400 litres utiles + 160litres en moyenne, pour le d\u00e9gazage avec effet acc\u00e9l\u00e9rateur dans les compartiments apport et maturation. 3 bacs en 1 meuble avec 800 litres pour l\u2019apport, 800litres pour le broyat, 800 litres pour la maturation.<\/li>\n\n\n\n<li><strong>Ing\u00e9nierie super fiable :<\/strong>&nbsp;Notre exp\u00e9rience de dix ans de cr\u00e9ation de composteurs vous garantit un fonctionnement optimal pour des ann\u00e9es de service en tous lieux et toute m\u00e9t\u00e9o.<\/li>\n\n\n\n<li><strong>Montage facile :<\/strong>&nbsp;Livr\u00e9 en kit, le montage se fait en 60 minutes avec une visseuse. L\u2019assemblage Il est pr\u00e9f\u00e9rable d\u2019\u00eatre deux pour le montage.<\/li>\n\n\n\n<li><strong>Dur\u00e9e de vie :<\/strong>&nbsp;R\u00e9alis\u00e9 avec sens et passion, nos composteurs ne sont pas cens\u00e9s casser avant 6 \u00e0 10 ans ou plus (suivant les contraintes locales). Ce mod\u00e8le con\u00e7u avec les m\u00eames mat\u00e9riaux que les gros composteurs b\u00e9n\u00e9ficient d\u2019une solidit\u00e9 extr\u00eame.<\/li>\n\n\n\n<li><strong>Entretien :<\/strong>&nbsp;Aucun entretien n\u2019est n\u00e9cessaire gr\u00e2ce \u00e0 la haute qualit\u00e9 de tous nos mat\u00e9riaux. Le bois ne doit pas \u00eatre impr\u00e9gn\u00e9 de substance qui pourrait entraver sa fonction r\u00e9gulant l\u2019humidit\u00e9.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"pavillons\">Les pavillons:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les aires de compostage grande capacit\u00e9 :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con\u00e7u pour traiter de gros volumes, ce mod\u00e8le s\u2019ajuste \u00e0 vos besoins en multipliant les alv\u00e9oles. Une alv\u00e9ole contient 1400 litres.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/compost.equipment\/wp-content\/uploads\/2025\/01\/IMG_20211113_111627-edited-scaled.jpg\" alt=\"\" class=\"wp-image-213\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">&#8211; <strong>3 alv\u00e9oles:<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4200 litres<\/strong>&nbsp;+ 1 espace de mati\u00e8res s\u00e8ches (1400 litres)<strong>De 4 \u00e0 6 tonnes<\/strong>&nbsp;de d\u00e9chets \u00e0 traiter par an,&nbsp;<strong>3 alv\u00e9oles (4200 litres)<\/strong>&nbsp;+ 1 espace de mati\u00e8res s\u00e8ches (1400 litres.&nbsp;<strong>Prix du pavillon + installation : 4700,00\u20ac + forfait km.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En option, le kit anti rat complet et indestructible, dessus sur charni\u00e8res + dessous 2040\u20ac<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">&#8211; <strong>6 alv\u00e9oles:<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>8400 litres<\/strong>&nbsp;+ 1 espace de mati\u00e8res s\u00e8ches 2400 litres.&nbsp;<strong>De 8 \u00e0 12 Tonnes<\/strong>&nbsp;de d\u00e9chets \u00e0 traiter par an, .&nbsp;<strong>Prix du pavillon + installation : 9400,00\u20ac + forfait km.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En option, le kit anti rat complet et indestructible, dessus sur charni\u00e8res + dessous 3990\u20ac<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">&#8211; <strong>9 alv\u00e9oles<\/strong>:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>12600 litres&nbsp;+ 1 espace de mati\u00e8res s\u00e8ches (4200 litres<\/strong>. De 10 \u00e0 18 Tonnes \u00e0 traiter de d\u00e9chets par an.&nbsp;<strong>Prix du pavillon + installation : 14000,00\u20ac + forfait km.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemple d\u2019emprise au sol<\/strong>&nbsp;: 9 bacs de 1400 litres = 12 000 litres d\u00e9di\u00e9s au compost. Dimensions au sol : 12 m. x 1,50 m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En option<\/strong>&nbsp;: Goutti\u00e8re et r\u00e9cup\u00e9rateur d\u2019eau avec habillage de la cuve en bois douglas, veuillez nous consulter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">volume de broyat correspondant (non couvert) + 1 espace de rangement des planches ou des outils.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les accessoires:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"bacs-rubans\">&#8211; Les bacs rubans \u00e0 don de compost mature :<\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/compost.equipment\/wp-content\/uploads\/2025\/01\/20240428_170503-768x1024.jpg\" alt=\"\" class=\"wp-image-92\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Autrement qu\u2019en cube standard, nous vous proposons ce mod\u00e8le unique \u00e0 d\u00e9ployer selon la forme que vous voulez. En bande de planches de douglas rabot\u00e9 de 25mm d\u2019\u00e9paisseur, 160 cm de long \u00e0 d\u00e9rouler et disposer comme on veut (on multiplie simplement les bandes pour plus de volume).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"coffre-a-outils\">&#8211; Les coffres \u00e0 outils :&nbsp;<strong>&nbsp;<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/compost.equipment\/wp-content\/uploads\/2025\/01\/IMG_20250116_192939-edited.jpg\" alt=\"\" class=\"wp-image-215\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tr\u00e8s compacts et solides, ces coffres sont pr\u00e9vus pour s\u00e9curiser votre mat\u00e9riel.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vous l\u2019installerez en 10 minutes sur n\u2019importe quel mod\u00e8le Divesterram.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il est pr\u00e9vu pour contenir :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>3 outils \u00e0 manche long (pelle, balais, fourche\u2026)<\/li>\n\n\n\n<li>1 arrosoir<\/li>\n\n\n\n<li>1 b\u00e2che<\/li>\n\n\n\n<li>1 brasseur \u00e0 compost<\/li>\n\n\n\n<li>1 thermom\u00e8tre<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">(Outils non fournis !)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fermeture est \u00e0 cadenasser&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"porte-panneau\">&#8211; Les portes panneaux :<\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/compost.equipment\/wp-content\/uploads\/2025\/01\/IMG_1795-edited-1.jpg\" alt=\"\" class=\"wp-image-218\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Destin\u00e9s \u00e0 informer les utilisateurs, les panneaux sont \u00e0 placer au-dessus et \u00e0 l\u2019arri\u00e8re des composteurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9alisation en montants de douglas rabot\u00e9, ils sont adaptables \u00e0 vos tailles sp\u00e9cifiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ils sont tr\u00e8s solides et r\u00e9sistants dans le temps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"grille\">&#8211; Grille anti-rat:<\/h3>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>400: 75\u20ac HT.<\/li>\n\n\n\n<li>600: 87\u20ac HT.<\/li>\n\n\n\n<li>800: 98\u20ac HT.<\/li>\n\n\n\n<li>1000: 110\u20ac HT<\/li>\n\n\n\n<li>1800: 160\u20ac HT.<\/li>\n\n\n\n<li>2400: 187\u20ac HT.<\/li>\n\n\n\n<li>Pavillon 3: 480\u20ac HT.<\/li>\n\n\n\n<li>Pavillon 6: 610\u20ac HT.<\/li>\n\n\n\n<li>Pavillon 9: 830\u20ac HT.<\/li>\n\n\n\n<li>900 PME: 75\u20ac HT.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading\">Les mod\u00e8les sp\u00e9ciaux:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"400litres-eternel\">&#8211; Le sp\u00e9cial 400litres en ch\u00e2taigner:&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>le composteur Eternel!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/compost.equipment\/wp-content\/uploads\/2025\/01\/IMG_20250131_171533-edited.jpg\" alt=\"\" class=\"wp-image-205\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Le mod\u00e8le id\u00e9al pour permettre aux familles de composter facilement.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Dans le bac il y a une s\u00e9paration pour cr\u00e9er une r\u00e9serve \u00e0 broyat de 70 litres.<\/em><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Capacit\u00e9 de traitement :<\/strong>&nbsp;apport quotidien de 2 \u00e0 6 personnes.<\/li>\n\n\n\n<li><strong>Ing\u00e9nierie super fiable :<\/strong>&nbsp;Notre exp\u00e9rience de dix ans de cr\u00e9ation de composteurs vous garantit un fonctionnement optimal pour des ann\u00e9es de service en tous lieux et toute m\u00e9t\u00e9o.<\/li>\n\n\n\n<li><strong>Montage facile :<\/strong>&nbsp;Livr\u00e9 en kit, le montage se fait en 15 minutes avec une visseuse. L\u2019assemblage peut se faire par une personne seule et la notice ainsi que la visserie sont fournis dans le kit.<\/li>\n\n\n\n<li><strong>Dur\u00e9e de vie :<\/strong>&nbsp;R\u00e9alis\u00e9 avec sens et passion, ce mod\u00e8le est simplement ETERNEL! Ce mod\u00e8le con\u00e7u avec les m\u00eames techniques que les gros composteurs mais en bois de ch\u00e2taigner, b\u00e9n\u00e9ficient d\u2019une solidit\u00e9 extr\u00eame.<\/li>\n\n\n\n<li><strong>Entretien :<\/strong>&nbsp;Aucun entretien n\u2019est n\u00e9cessaire gr\u00e2ce \u00e0 la haute qualit\u00e9 de tous nos mat\u00e9riaux. Le bois ne doit pas \u00eatre impr\u00e9gn\u00e9 de substance qui pourrait entraver sa fonction r\u00e9gulant l\u2019humidit\u00e9.<\/li>\n\n\n\n<li><strong>Informations compl\u00e9mentaires :<\/strong>&nbsp;Merci de consulter la fiche de pr\u00e9sentation technique.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le Sp\u00e9cial 900 litres:<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"442654\" src=\"https:\/\/divesterram.fr\/wp-content\/uploads\/2024\/02\/IMG_1439-1024x683.jpg\" alt=\"\" class=\"wp-image-442654\" srcset=\"https:\/\/divesterram.fr\/wp-content\/uploads\/2024\/02\/IMG_1439-1024x683.jpg 1024w, https:\/\/divesterram.fr\/wp-content\/uploads\/2024\/02\/IMG_1439-300x200.jpg 300w, https:\/\/divesterram.fr\/wp-content\/uploads\/2024\/02\/IMG_1439-768x512.jpg 768w, https:\/\/divesterram.fr\/wp-content\/uploads\/2024\/02\/IMG_1439-1536x1024.jpg 1536w, https:\/\/divesterram.fr\/wp-content\/uploads\/2024\/02\/IMG_1439-2048x1365.jpg 2048w, https:\/\/divesterram.fr\/wp-content\/uploads\/2024\/02\/IMG_1439-1200x800.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n<\/figure>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/divesterram.fr\/wp-content\/uploads\/2024\/02\/Fiche-technique-du-special-900-litres.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 Fiche-technique-du-special-900-litres.\"><\/object><a id=\"wp-block-file--media-5af5e2b4-a988-4d72-87c1-6797674ccc22\" href=\"https:\/\/divesterram.fr\/wp-content\/uploads\/2024\/02\/Fiche-technique-du-special-900-litres.pdf\">Fiche-technique-du-special-900-litres<\/a><a href=\"https:\/\/divesterram.fr\/wp-content\/uploads\/2024\/02\/Fiche-technique-du-special-900-litres.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-5af5e2b4-a988-4d72-87c1-6797674ccc22\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Nous avons con\u00e7u ce mod\u00e8le pour les  structures de 15 \u00e0 20 personnes.<\/strong><\/li>\n\n\n\n<li><strong>Capacit\u00e9 de traitement:<\/strong> apport de 350 litres utiles + maturation 350 litres +  bac grillag\u00e9 pour le broyat et  un bac de distribution du compost mature.<\/li>\n\n\n\n<li><strong>Ing\u00e9nierie super fiable:<\/strong> Notre exp\u00e9rience de dix ans de cr\u00e9ation de composteurs vous garanti un fonctionnement optimal pour des ann\u00e9es de service en tous lieux et toute m\u00e9t\u00e9o.<\/li>\n\n\n\n<li><strong>Montage facile:<\/strong> Livr\u00e9 en kit, le montage se fait en 25minutes avec une visseuse. L\u2019assemblage peut se faire par une personne seule et la notice ainsi que la visserie sont fournis dans le kit.<\/li>\n\n\n\n<li><strong>Dur\u00e9e de vie:<\/strong> R\u00e9alis\u00e9 avec sens et passion, nos composteurs ne sont pas sens\u00e9 casser avant 6 \u00e0 10 ans ou plus (suivant les contraintes locales). Ce mod\u00e8le con\u00e7u avec les m\u00eames mat\u00e9riaux que les gros composteurs b\u00e9n\u00e9ficie d\u2019une solidit\u00e9 extr\u00eame.<\/li>\n\n\n\n<li><strong>Entretien:<\/strong> Aucun entretien n\u2019est n\u00e9cessaire gr\u00e2ce \u00e0 la haute qualit\u00e9 de tous nos mat\u00e9riaux. Le bois ne doit pas \u00eatre impr\u00e9gn\u00e9 de substance qui pourrait entraver sa fonction r\u00e9gulant l\u2019humidit\u00e9.<\/li>\n\n\n\n<li><strong>Informations compl\u00e9mentaires:<\/strong> Merci de consulter la fiche de pr\u00e9sentation technique.                                                                                                                                          <strong>Tarif et modalit\u00e9 de livraison<\/strong>:<\/li>\n\n\n\n<li>Prix \u00e0 l\u2019unit\u00e9 :  970\u20ac HT.   <\/li>\n\n\n\n<li>Prix transport: Nous consulter, gratuit en dessous de 50km a\/r.<\/li>\n\n\n\n<li>D\u00e9lais de livraison: Moins de 10 jours pour 10 unit\u00e9s.<\/li>\n\n\n\n<li>Livraison: en lot sur palette.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-bright-blue-color has-text-color wp-block-paragraph\"><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tous nos prix sont H.T. et n&rsquo;incluent pas le service de livraison. Nos mod\u00e8les sont d\u00e9pos\u00e9s, leur reproduction est interdite. Les monobac: Les tribacs: Les pavillons grande capacit\u00e9: Les accessoires: Les mod\u00e8les sp\u00e9ciaux: Les monobac: Nous avons con\u00e7u ces mod\u00e8les pour une utilisation en tous lieu et pour augmenter le volume des installations tribacs 1800 &hellip; <a href=\"https:\/\/divesterram.fr\/index.php\/tarifs\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Tarifs 2026&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-233482","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tous nos prix sont H.T. et n&#039;incluent pas le service de livraison. Nos mod\u00e8les sont d\u00e9pos\u00e9s, leur reproduction est interdite. Les monobac: Le 600 litres 1 fa\u00e7ade et 1 capot \u00e0 480 \u20ac HT. Le 800 litres 2 fa\u00e7ades et 1 capot \u00e0 560\u20ac HT. Le 1000 litres 2 fa\u00e7ades et 2 capots \u00e0 670\u20ac\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"gnMMsPhRrfHc9lzyC4TF7U3hG2lSNk8RpHoIkO_pXIY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/divesterram.fr\/index.php\/tarifs\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/divesterram.fr\\\/index.php\\\/tarifs\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/divesterram.fr#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/divesterram.fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/divesterram.fr\\\/index.php\\\/tarifs\\\/#listItem\",\"name\":\"Tarifs 2026\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/divesterram.fr\\\/index.php\\\/tarifs\\\/#listItem\",\"position\":2,\"name\":\"Tarifs 2026\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/divesterram.fr#listItem\",\"name\":\"Accueil\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/divesterram.fr\\\/#organization\",\"name\":\"SARL COMETTO VIALA Divesterram\",\"description\":\"Les composteurs de qualit\\u00e9!\",\"url\":\"https:\\\/\\\/divesterram.fr\\\/\",\"telephone\":\"+33638024425\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/divesterram.fr\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/IMG_20220405_160029-scaled.jpg\",\"@id\":\"https:\\\/\\\/divesterram.fr\\\/index.php\\\/tarifs\\\/#organizationLogo\",\"width\":2560,\"height\":1920},\"image\":{\"@id\":\"https:\\\/\\\/divesterram.fr\\\/index.php\\\/tarifs\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/youtube.com\\\/Emmanuel Cometto\",\"https:\\\/\\\/linkedin.com\\\/in\\\/Emmanuel Cometto\",\"https:\\\/\\\/profiles.wordpress.org\\\/Emmanuel Cometto\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/divesterram.fr\\\/index.php\\\/tarifs\\\/#webpage\",\"url\":\"https:\\\/\\\/divesterram.fr\\\/index.php\\\/tarifs\\\/\",\"name\":\"Tarifs 2026 | Divesterram\",\"description\":\"Tous nos prix sont H.T. et n'incluent pas le service de livraison. Nos mod\\u00e8les sont d\\u00e9pos\\u00e9s, leur reproduction est interdite. Les monobac: Le 600 litres 1 fa\\u00e7ade et 1 capot \\u00e0 480 \\u20ac HT. Le 800 litres 2 fa\\u00e7ades et 1 capot \\u00e0 560\\u20ac HT. Le 1000 litres 2 fa\\u00e7ades et 2 capots \\u00e0 670\\u20ac\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/divesterram.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/divesterram.fr\\\/index.php\\\/tarifs\\\/#breadcrumblist\"},\"datePublished\":\"2023-01-29T23:43:51+01:00\",\"dateModified\":\"2026-02-02T10:03:27+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/divesterram.fr\\\/#website\",\"url\":\"https:\\\/\\\/divesterram.fr\\\/\",\"name\":\"Divesterram sp\\u00e9cialiste du compostage depuis 2014\",\"alternateName\":\"\\u00e9quipement de compostage\",\"description\":\"Les composteurs de qualit\\u00e9!\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/divesterram.fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Tarifs 2026 | Divesterram<\/title>\n\n","aioseo_head_json":{"title":"Tarifs 2026 | Divesterram","description":"Tous nos prix sont H.T. et n'incluent pas le service de livraison. Nos mod\u00e8les sont d\u00e9pos\u00e9s, leur reproduction est interdite. Les monobac: Le 600 litres 1 fa\u00e7ade et 1 capot \u00e0 480 \u20ac HT. Le 800 litres 2 fa\u00e7ades et 1 capot \u00e0 560\u20ac HT. Le 1000 litres 2 fa\u00e7ades et 2 capots \u00e0 670\u20ac","canonical_url":"https:\/\/divesterram.fr\/index.php\/tarifs\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"gnMMsPhRrfHc9lzyC4TF7U3hG2lSNk8RpHoIkO_pXIY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/divesterram.fr\/index.php\/tarifs\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/divesterram.fr#listItem","position":1,"name":"Accueil","item":"https:\/\/divesterram.fr","nextItem":{"@type":"ListItem","@id":"https:\/\/divesterram.fr\/index.php\/tarifs\/#listItem","name":"Tarifs 2026"}},{"@type":"ListItem","@id":"https:\/\/divesterram.fr\/index.php\/tarifs\/#listItem","position":2,"name":"Tarifs 2026","previousItem":{"@type":"ListItem","@id":"https:\/\/divesterram.fr#listItem","name":"Accueil"}}]},{"@type":"Organization","@id":"https:\/\/divesterram.fr\/#organization","name":"SARL COMETTO VIALA Divesterram","description":"Les composteurs de qualit\u00e9!","url":"https:\/\/divesterram.fr\/","telephone":"+33638024425","logo":{"@type":"ImageObject","url":"https:\/\/divesterram.fr\/wp-content\/uploads\/2022\/04\/IMG_20220405_160029-scaled.jpg","@id":"https:\/\/divesterram.fr\/index.php\/tarifs\/#organizationLogo","width":2560,"height":1920},"image":{"@id":"https:\/\/divesterram.fr\/index.php\/tarifs\/#organizationLogo"},"sameAs":["https:\/\/youtube.com\/Emmanuel Cometto","https:\/\/linkedin.com\/in\/Emmanuel Cometto","https:\/\/profiles.wordpress.org\/Emmanuel Cometto"]},{"@type":"WebPage","@id":"https:\/\/divesterram.fr\/index.php\/tarifs\/#webpage","url":"https:\/\/divesterram.fr\/index.php\/tarifs\/","name":"Tarifs 2026 | Divesterram","description":"Tous nos prix sont H.T. et n'incluent pas le service de livraison. Nos mod\u00e8les sont d\u00e9pos\u00e9s, leur reproduction est interdite. Les monobac: Le 600 litres 1 fa\u00e7ade et 1 capot \u00e0 480 \u20ac HT. Le 800 litres 2 fa\u00e7ades et 1 capot \u00e0 560\u20ac HT. Le 1000 litres 2 fa\u00e7ades et 2 capots \u00e0 670\u20ac","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/divesterram.fr\/#website"},"breadcrumb":{"@id":"https:\/\/divesterram.fr\/index.php\/tarifs\/#breadcrumblist"},"datePublished":"2023-01-29T23:43:51+01:00","dateModified":"2026-02-02T10:03:27+01:00"},{"@type":"WebSite","@id":"https:\/\/divesterram.fr\/#website","url":"https:\/\/divesterram.fr\/","name":"Divesterram sp\u00e9cialiste du compostage depuis 2014","alternateName":"\u00e9quipement de compostage","description":"Les composteurs de qualit\u00e9!","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/divesterram.fr\/#organization"}}]}},"aioseo_meta_data":{"post_id":"233482","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-08-01 09:52:46","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-01-29 22:43:33","updated":"2026-08-01 09:52:46","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/divesterram.fr\" title=\"Accueil\">Accueil<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tTarifs 2026\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/divesterram.fr"},{"label":"Tarifs 2026","link":"https:\/\/divesterram.fr\/index.php\/tarifs\/"}],"_links":{"self":[{"href":"https:\/\/divesterram.fr\/index.php\/wp-json\/wp\/v2\/pages\/233482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divesterram.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/divesterram.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/divesterram.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/divesterram.fr\/index.php\/wp-json\/wp\/v2\/comments?post=233482"}],"version-history":[{"count":46,"href":"https:\/\/divesterram.fr\/index.php\/wp-json\/wp\/v2\/pages\/233482\/revisions"}],"predecessor-version":[{"id":586739,"href":"https:\/\/divesterram.fr\/index.php\/wp-json\/wp\/v2\/pages\/233482\/revisions\/586739"}],"wp:attachment":[{"href":"https:\/\/divesterram.fr\/index.php\/wp-json\/wp\/v2\/media?parent=233482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}